{"id":3416,"date":"2025-03-05T11:19:52","date_gmt":"2025-03-05T09:19:52","guid":{"rendered":"https:\/\/talesofmemories.com\/product\/pagina-recuerdos\/"},"modified":"2025-05-07T10:15:00","modified_gmt":"2025-05-07T07:15:00","slug":"pagina-recuerdos","status":"publish","type":"product","link":"https:\/\/talesofmemories.com\/es\/producto\/pagina-recuerdos\/","title":{"rendered":"Recuerdos"},"content":{"rendered":"<p data-start=\"68\" data-end=\"310\">No todos los recuerdos son sobre personas: a veces queremos <strong data-start=\"123\" data-end=\"208\">conservar la historia de una empresa, un grupo de m\u00fasica, un acontecimiento u otra historia significativa<\/strong>. La <strong data-start=\"214\" data-end=\"231\">p\u00e1gina de recuerdos<\/strong> te permite <strong data-start=\"246\" data-end=\"307\">documentar hitos importantes y almacenarlos en un solo lugar<\/strong>. <\/p>\n<p data-start=\"312\" data-end=\"517\">A\u00f1ade <strong data-start=\"316\" data-end=\"350\">fotos, v\u00eddeos y una cronolog\u00eda<\/strong> para marcar <strong data-start=\"359\" data-end=\"420\">acontecimientos clave, logros y momentos inolvidables<\/strong>. La p\u00e1gina de recuerdos <strong data-start=\"438\" data-end=\"514\">mantiene viva la historia y facilita que se comparta con quienes la valoran<\/strong>. <\/p>\n<p data-start=\"519\" data-end=\"710\"><strong data-start=\"519\" data-end=\"571\">Con un c\u00f3digo QR, los recuerdos est\u00e1n siempre al alcance de la mano: <\/strong>col\u00f3calo en <strong data-start=\"584\" data-end=\"654\">las instalaciones de una empresa, en los carteles de un concierto o en una placa conmemorativa<\/strong>, asegur\u00e1ndote de que la historia est\u00e1 <strong data-start=\"690\" data-end=\"707\">a un solo escaneo de distancia<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conserva una historia que merece perdurar<\/p>\n","protected":false},"featured_media":3417,"template":"","meta":{"inline_featured_image":false},"product_brand":[267],"product_cat":[162],"product_tag":[],"class_list":{"0":"post-3416","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-recuerdos","7":"product_cat-paginas-es","9":"first","10":"instock","11":"sale","12":"sold-individually","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/product\/3416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/media\/3417"}],"wp:attachment":[{"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/media?parent=3416"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/product_brand?post=3416"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/product_cat?post=3416"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/talesofmemories.com\/es\/wp-json\/wp\/v2\/product_tag?post=3416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}